{"id":12448,"date":"2024-03-21T17:08:37","date_gmt":"2024-03-21T15:08:37","guid":{"rendered":"https:\/\/globaleyewitnessnews.com\/roseanne-barr-diz-ao-gen-nos-estados-unidos-todos-os-nossos-comediantes-praticam-a-autocensura\/"},"modified":"2024-03-24T15:53:52","modified_gmt":"2024-03-24T13:53:52","slug":"roseanne-barr-diz-ao-gen-nos-estados-unidos-todos-os-nossos-comediantes-praticam-a-autocensura","status":"publish","type":"post","link":"https:\/\/globaleyewitnessnews.com\/pt-br\/roseanne-barr-diz-ao-gen-nos-estados-unidos-todos-os-nossos-comediantes-praticam-a-autocensura\/","title":{"rendered":"Roseanne Barr diz ao GEN: &#8216;Nos Estados Unidos, todos os nossos comediantes praticam a autocensura&#8217;"},"content":{"rendered":"\n<p>A comediante Roseanne Barr reagiu hoje a um v\u00eddeo que mostra a pol\u00edcia de Amsterd\u00e3 invadindo a casa do comediante holand\u00eas Hans Teeuwen, horas depois de ele ter parodiado a prefeita da cidade.<\/p>\n\n<p>Ao ser perguntadoa se os comediantes dos Estados Unidos sentem essa censura, Barr disse ao <a href=\"https:\/\/globaleyewitnessnews.com\/pt-br\/\">Global Eyewitness News<\/a>: &#8220;Nos Estados Unidos, todos os nossos comediantes praticam a autocensura &#8211; em sua maior parte, e N\u00c3O OUSAM discordar de Obama Inc.&#8221;.<\/p>\n\n<figure class=\"wp-block-video\"><video height=\"452\" style=\"aspect-ratio: 256 \/ 452;\" width=\"256\" controls=\"\" src=\"https:\/\/globaleyewitnessnews.com\/wp-content\/uploads\/2024\/03\/Police-visit-Dutch-comedian-over-criticism-of-Amsterdam-mayor.mp4\"><\/video><figcaption class=\"wp-element-caption\">Pol\u00edcia de Amsterd\u00e3 visita o comediante Hans Teeuwen por causa de cr\u00edticas \u00e0 prefeita<\/figcaption><\/figure>\n\n<p>Seis policiais invadiram a casa do comediante Hans Teeuwen em Amsterd\u00e3 na ter\u00e7a-feira, informou o <a href=\"https:\/\/nltimes.nl\/2024\/03\/12\/police-raid-amsterdam-comedian-hans-teeuwens-home-hours-parody-citys-mayor\">NL Times<\/a>. A batida ocorreu horas depois de Teeuwen ter <a href=\"https:\/\/www.instagram.com\/reel\/C4aW_Ceou5Z\">publicado um v\u00eddeo nas redes sociais<\/a> em que um objeto com a apar\u00eancia de uma arma de fogo pode ser visto em uma mesa pr\u00f3xima a ele. Com uma peruca preta e grossa, Teeuwen parodiou a prefeita Femke Halsema.<\/p><div id=\"globa-1931815176\" class=\"globa-content globa-entity-placement\"><a href=\"https:\/\/www.givesendgo.com\/globaleyewitnessnews\" aria-label=\"GEN crowdfunder banner ad\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/globaleyewitnessnews.com\/wp-content\/uploads\/2024\/01\/GEN-Banner-Ad-2.png\" alt=\"GEN crowdfunder banner ad\"  srcset=\"https:\/\/globaleyewitnessnews.com\/wp-content\/uploads\/2024\/01\/GEN-Banner-Ad-2.png 2000w, https:\/\/globaleyewitnessnews.com\/wp-content\/uploads\/2024\/01\/GEN-Banner-Ad-2-300x90.png 300w, https:\/\/globaleyewitnessnews.com\/wp-content\/uploads\/2024\/01\/GEN-Banner-Ad-2-1024x307.png 1024w, https:\/\/globaleyewitnessnews.com\/wp-content\/uploads\/2024\/01\/GEN-Banner-Ad-2-768x230.png 768w, https:\/\/globaleyewitnessnews.com\/wp-content\/uploads\/2024\/01\/GEN-Banner-Ad-2-1536x461.png 1536w, https:\/\/globaleyewitnessnews.com\/wp-content\/uploads\/2024\/01\/GEN-Banner-Ad-2-860x258.png 860w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" width=\"2000\" height=\"600\"   \/><\/a><\/div>\n\n<p>O v\u00eddeo mostra o comediante atendendo \u00e0 porta da frente enquanto seis policiais est\u00e3o do lado de fora de sua casa. Teeuwen esclareceu que a pol\u00edcia estava l\u00e1 por causa de &#8220;um adere\u00e7o&#8221;. Teeuwen ent\u00e3o consentiu com a entrada da pol\u00edcia.  <\/p>\n\n<p>Ao questionar o motivo de os policiais estarem em sua casa, um deles disse que isso estava relacionado \u00e0 lei que rege as armas de fogo na Holanda e ao que &#8220;algu\u00e9m viu no v\u00eddeo curto&#8221;. A lei holandesa pro\u00edbe estritamente a posse de objetos que sejam muito semelhantes a armas de fogo. Um porta-voz da pol\u00edcia confirmou que um &#8220;indiv\u00edduo preocupado&#8221; entrou em contato com eles ap\u00f3s avistar a arma.  <\/p>\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">\ud83d\udc40 Jim Breuer: \u201cWe\u2019re at war\u2026Unfortunately humanity doesn\u2019t believe that evil exists. And boy, does it exist. And you\u2019d be horrified when you realize where they\u2019re all located.\u201d <a href=\"https:\/\/t.co\/Sqet1cZYGE\">pic.twitter.com\/Sqet1cZYGE<\/a><\/p>&mdash; Chief Nerd (@TheChiefNerd) <a href=\"https:\/\/twitter.com\/TheChiefNerd\/status\/1733905773296595360?ref_src=twsrc%5Etfw\">December 10, 2023<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><figcaption class=\"wp-element-caption\">O comediante Jim Breuer fala sobre &#8220;prefeitos desprez\u00edveis&#8221; e totalitarismo<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>A comediante Roseanne Barr reagiu hoje a um v\u00eddeo que mostra a pol\u00edcia de Amsterd\u00e3 invadindo a casa do comediante holand\u00eas Hans Teeuwen, horas depois de ele ter parodiado a prefeita da cidade. Ao ser perguntadoa se os comediantes dos Estados Unidos sentem essa censura, Barr disse ao Global Eyewitness News: &#8220;Nos Estados Unidos, todos [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":12282,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","wds_primary_category":0,"footnotes":""},"categories":[138,263],"tags":[152,325,141,326,324,285],"class_list":{"0":"post-12448","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-eua","8":"category-resistencia-pt-br","9":"tag-censura","10":"tag-comedia","11":"tag-globalismo","12":"tag-liberdade-de-expressao","13":"tag-roseanne-barr-pt-br","14":"tag-wokeness-pt-br"},"_links":{"self":[{"href":"https:\/\/globaleyewitnessnews.com\/pt-br\/wp-json\/wp\/v2\/posts\/12448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globaleyewitnessnews.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globaleyewitnessnews.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globaleyewitnessnews.com\/pt-br\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globaleyewitnessnews.com\/pt-br\/wp-json\/wp\/v2\/comments?post=12448"}],"version-history":[{"count":1,"href":"https:\/\/globaleyewitnessnews.com\/pt-br\/wp-json\/wp\/v2\/posts\/12448\/revisions"}],"predecessor-version":[{"id":12449,"href":"https:\/\/globaleyewitnessnews.com\/pt-br\/wp-json\/wp\/v2\/posts\/12448\/revisions\/12449"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globaleyewitnessnews.com\/pt-br\/wp-json\/wp\/v2\/media\/12282"}],"wp:attachment":[{"href":"https:\/\/globaleyewitnessnews.com\/pt-br\/wp-json\/wp\/v2\/media?parent=12448"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globaleyewitnessnews.com\/pt-br\/wp-json\/wp\/v2\/categories?post=12448"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globaleyewitnessnews.com\/pt-br\/wp-json\/wp\/v2\/tags?post=12448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}