{"id":8902,"date":"2024-01-30T16:03:16","date_gmt":"2024-01-30T14:03:16","guid":{"rendered":"https:\/\/globaleyewitnessnews.com\/sororidad-nacional-de-mujeres-considera-nombrar-lider-masculino\/"},"modified":"2024-02-13T15:02:29","modified_gmt":"2024-02-13T13:02:29","slug":"sororidad-nacional-de-mujeres-considera-nombrar-lider-masculino","status":"publish","type":"post","link":"https:\/\/globaleyewitnessnews.com\/es\/sororidad-nacional-de-mujeres-considera-nombrar-lider-masculino\/","title":{"rendered":"Sororidad nacional de mujeres considera nombrar l\u00edder masculino"},"content":{"rendered":"\n<p class=\"\">Por primera vez en la historia, una sororidad nacional de mujeres podr\u00eda designar como presidente a un hombre que dice creer que es una mujer.<\/p>\n\n\n\n<p class=\"\">Exalumnas de Kappa Kappa Gamma (KKG) presentaron una demanda para impedir que la sororidad acepte como miembros a hombres que afirman ser mujeres. Seg\u00fan la denuncia, KKG est\u00e1 considerando ahora a Tom Nadzieja para un puesto de liderazgo que puede incluir un puesto en el Consejo de la Sororidad o la presidencia. <\/p>\n\n\n\n<p class=\"\">Nadzieja, quien abandon\u00f3 a su esposa e hijos despu\u00e9s de 15 a\u00f1os de matrimonio y cambi\u00f3 su nombre a Tracy, se ha centrado en difundir la ideolog\u00eda de g\u00e9nero, particularmente entre los j\u00f3venes. Sigue siendo miembro de la junta directiva de one-n-ten, una organizaci\u00f3n sin fines de lucro que <a href=\"https:\/\/www.dailywire.com\/news\/pediatric-gender-clinics-scrub-their-websites-amidst-criticism-of-gender-related-treatments\">ayuda<\/a> a ni\u00f1os a sufrir mutilaci\u00f3n genital. <\/p><div id=\"globa-1288588536\" class=\"globa-content globa-entity-placement\"><a href=\"https:\/\/www.givesendgo.com\/globaleyewitnessnews\" aria-label=\"GEN crowdfunder banner ad\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/globaleyewitnessnews.com\/wp-content\/uploads\/2024\/01\/GEN-Banner-Ad-2.png\" alt=\"GEN crowdfunder banner ad\"  srcset=\"https:\/\/globaleyewitnessnews.com\/wp-content\/uploads\/2024\/01\/GEN-Banner-Ad-2.png 2000w, https:\/\/globaleyewitnessnews.com\/wp-content\/uploads\/2024\/01\/GEN-Banner-Ad-2-300x90.png 300w, https:\/\/globaleyewitnessnews.com\/wp-content\/uploads\/2024\/01\/GEN-Banner-Ad-2-1024x307.png 1024w, https:\/\/globaleyewitnessnews.com\/wp-content\/uploads\/2024\/01\/GEN-Banner-Ad-2-768x230.png 768w, https:\/\/globaleyewitnessnews.com\/wp-content\/uploads\/2024\/01\/GEN-Banner-Ad-2-1536x461.png 1536w, https:\/\/globaleyewitnessnews.com\/wp-content\/uploads\/2024\/01\/GEN-Banner-Ad-2-860x258.png 860w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" width=\"2000\" height=\"600\"   \/><\/a><\/div>\n\n\n\n<p class=\"\">\u201cActualmente el Candidato ha solicitado, y est\u00e1 siendo considerado, para un puesto de liderazgo que se votar\u00e1 mediante una elecci\u00f3n en l\u00ednea en abril de 2024,\u201d se lee en la demanda, <a href=\"https:\/\/www.dailywire.com\/news\/trans-identifying-man-may-become-first-male-president-of-a-national-sorority-says-lawsuit\">seg\u00fan<\/a> <em>Daily Wire<\/em>. \u201cEste puesto podr\u00eda incluir ser elegido miembro del [the]Consejo de Sororidad o incluso presidente de KKG. La mayor\u00eda de las miembros desconocen que el Candidato es un hombre\u201d.<\/p>\n\n\n\n<p class=\"\">Las exalumnas que presentaron la denuncia son Patsy Levang, Cheryl Tuck-Smith, Susan Jennings, Margo Knorr, Karen Pope y Ann Witt. Levang y Tuck-Smith fueron miembros de KKG durante m\u00e1s de 50 a\u00f1os, y Levang se desempe\u00f1\u00f3 como presidente de la Fundaci\u00f3n Nacional de KKG. Fueron expulsadas en noviembre por la direcci\u00f3n de KKG por oponerse a la afiliaci\u00f3n de hombres que afirman creerse mujeres.  <\/p>\n\n\n\n<p class=\"\">\u201cEl actual liderazgo de Kappa ha participado deliberadamente en una campa\u00f1a para socavar los estatutos de Kappa, lo que perjudica no s\u00f3lo a estas j\u00f3venes, sino a toda la organizaci\u00f3n,\u201d dijo Levang en un comunicado. \u201cNo me sorprende que tambi\u00e9n hayan ignorado el valor de la membres\u00eda vitalicia y mis 56 a\u00f1os de dedicaci\u00f3n al enviarme una carta de destituci\u00f3n.\u201d <\/p>\n\n\n\n<p class=\"\">Tuck-Smith expres\u00f3 su incredulidad de que el liderazgo de KKG est\u00e9 dispuesto a nombrar hombres para dirigir la sororidad despu\u00e9s de 150 a\u00f1os como una organizaci\u00f3n exclusivamente femenina.<\/p>\n\n\n\n<p class=\"\">\u201cEs incomprensible que el liderazgo actual descarte ese \u00e9xito al priorizar a los hombres sobre las mujeres,\u201d dijo Tuck-Smith. \u201cKappa debe permanecer fiel a su misi\u00f3n actual, apoyar y promover a las mujeres.\u201d <\/p>\n\n\n\n<p class=\"\"><em>GEN<\/em> <a href=\"https:\/\/globaleyewitnessnews.com\/es\/la-ideologia-de-genero-es-impuesta-por-las-mujeres-segun-muestran-datos\/\" target=\"_blank\" rel=\"noreferrer noopener\">inform\u00f3<\/a> anteriormente que la ideolog\u00eda de g\u00e9nero est\u00e1 siendo impuesta principalmente por mujeres, especialmente aquellas en posiciones de autoridad. Esta imposici\u00f3n incluye atacar a otras mujeres que se oponen a ellas.<\/p>\n\n\n\n<p class=\"\">Una <a href=\"https:\/\/www.pewresearch.org\/social-trends\/2022\/06\/28\/americans-complex-views-on-gender-identity-and-transgender-issues\/\">encuesta<\/a> realizada por <em>Pew Research<\/em> en 2022 encontr\u00f3 que el 62% de las mujeres cree que \u201chay mucha o bastante discriminaci\u00f3n contra las personas transg\u00e9nero.\u201d S\u00f3lo el 52% de los hombres est\u00e1 de acuerdo. Las mujeres exhiben una mayor tendencia que los hombres a expresar la creencia de que es de gran importancia utilizar el \u201cnuevo\u201d nombre o los \u201cpronombres preferidos\u201d de un individuo. <\/p>\n\n\n\n<p class=\"\"><a href=\"https:\/\/www.smh.com.au\/sport\/majority-of-female-athletes-support-the-inclusion-of-transgender-women-20220419-p5aehx.html\">Encuestas<\/a> adicionales realizadas en varias \u201cdemocracias,\u201d incluidas Australia, Inglaterra y Canad\u00e1, tambi\u00e9n han revelado que la mayor\u00eda de las atletas respaldan la participaci\u00f3n de los hombres en los deportes femeninos y no consideran que los hombres tengan una \u201cventaja injusta\u201d sobre las mujeres. Muchos hombres se oponen firmemente a esta opini\u00f3n.<\/p>\n\n\n\n<p class=\"\">En diciembre, la l\u00edder de una destacada organizaci\u00f3n de mujeres <a href=\"https:\/\/twitter.com\/DogRightGirl\/status\/1732144729846845454\">propuso<\/a> durante una audiencia en el Congreso, que ser\u00eda beneficioso que las chicas \u201caprendan a perder con gracia\u201d mientras compiten contra chicos que afirman ser chicas.<\/p>\n\n\n\n<p class=\"\">Durante esa misma audiencia en el Congreso, el comit\u00e9 tambi\u00e9n recibi\u00f3 el testimonio de Riley Gaines, una atleta de nataci\u00f3n que logr\u00f3 un empate en el quinto lugar en el campeonato de estilo libre de la NCAA junto a una persona que se identifica como \u201cLia\u201d Thomas y afirma su g\u00e9nero como mujer. Posteriormente, Gaines se ha convertido en una ferviente defensora de la oposici\u00f3n al dogma de g\u00e9nero y ha trabajado activamente para disuadir a los hombres de participar en deportes femeninos. <\/p>\n\n\n\n<p class=\"\">Sin embargo, fue una legisladora la que critic\u00f3 a Gaines en la audiencia debido a sus puntos de vista. La diputada Summer Lee (D-PA) describi\u00f3 a Gaines como \u201ctransf\u00f3bica\u201d debido a su oposici\u00f3n a la inclusi\u00f3n de hombres en los deportes femeninos. Luego de que Gaines respondiera y acusara a Lee de ser mis\u00f3gina, Lee intent\u00f3 suprimir los comentarios de la atleta del registro oficial.  <\/p>\n\n\n\n<p class=\"\">In April 2023, the US Department of En abril de 2023, el Departamento de Educaci\u00f3n de EE.UU. emiti\u00f3 una propuesta para prohibir que las escuelas excluyan a los hombres de los deportes femeninos. En respuesta, 25 gobernadores estadounidenses firmaron una carta expresando con urgencia que la administraci\u00f3n de Biden abandone o retrase la propuesta. La mayor\u00eda de los gobernadores, concretamente veintid\u00f3s de veinticinco, eran hombres. La carta fue firmada por tres gobernadoras, incluida la gobernadora de Arkansas, Sarah Huckabee Sanders, la gobernadora de Iowa, Kim Reynolds, y la gobernadora de Dakota del Sur, Kristi Noem. Estas tres gobernadoras son las \u00fanicas republicanas entre las 12 gobernadoras de Estados Unidos.    <\/p>\n\n\n\n<p class=\"\">Este problema no se limita a Estados Unidos.<\/p>\n\n\n\n<p class=\"\">En Irlanda, las funcionarias <a href=\"https:\/\/frontline.news\/es\/post\/gobierno-de-irlanda-en-negociaciones-para-definir-mujer-y-familia\">quieren<\/a> que la palabra \u201cmujer\u201d sea eliminada de la Constituci\u00f3n del pa\u00eds. <\/p>\n\n\n\n<p class=\"\">La directora ejecutiva del Servicio Penitenciario de Escocia, Teresa Medhurst, est\u00e1 <a href=\"https:\/\/frontline.news\/es\/post\/escocia-se-permite-a-hombres-que-se-hacen-pasar-por-mujeres-considerados-demasiado-peligrosos-para-las-carceles-de-mujeres-mezclarse-con-reclusas\">obligando<\/a> a las reclusas a ser alojadas con delincuentes varones violentos que afirman creer que son mujeres. El a\u00f1o pasado, la entonces primera ministra Nicola Sturgeon apoy\u00f3 la decisi\u00f3n de permitir que el violador en serie Adam Graham ingresara en la penitenciar\u00eda de mujeres, neg\u00e1ndose a reconocer que Bryson, que cambi\u00f3 su nombre a Isla Bryson, es un hombre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por primera vez en la historia, una sororidad nacional podr\u00eda designar como presidente a un hombre, que pretende ser mujer, como su presidente.<\/p>\n","protected":false},"author":2,"featured_media":5915,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","wds_primary_category":0,"footnotes":""},"categories":[135,137],"tags":[240],"class_list":{"0":"post-8902","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deportes-y-entretenimiento","8":"category-mundo","9":"tag-ideologia-de-genero-es"},"_links":{"self":[{"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/posts\/8902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/comments?post=8902"}],"version-history":[{"count":4,"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/posts\/8902\/revisions"}],"predecessor-version":[{"id":8917,"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/posts\/8902\/revisions\/8917"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/media\/5915"}],"wp:attachment":[{"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/media?parent=8902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/categories?post=8902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/tags?post=8902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}