{"id":5444,"date":"2024-01-02T13:23:35","date_gmt":"2024-01-02T11:23:35","guid":{"rendered":"https:\/\/globaleyewitness.news\/vuelven-las-advertencias-de-ciberpandemia-tras-ciberinvasion-china\/"},"modified":"2024-01-31T15:29:33","modified_gmt":"2024-01-31T13:29:33","slug":"vuelven-las-advertencias-de-ciberpandemia-tras-ciberinvasion-china","status":"publish","type":"post","link":"https:\/\/globaleyewitnessnews.com\/es\/vuelven-las-advertencias-de-ciberpandemia-tras-ciberinvasion-china\/","title":{"rendered":"Vuelven las advertencias de \u2018ciberpandemia\u2019 tras ciberinvasi\u00f3n china"},"content":{"rendered":"\n<p class=\"\">Un <a href=\"https:\/\/www.washingtonpost.com\/technology\/2023\/12\/11\/china-hacking-hawaii-pacific-taiwan-conflict\/\">art\u00edculo<\/a> reciente de <em>Washington Post<\/em> ha destacado una significativa intrusi\u00f3n cibern\u00e9tica llevada a cabo por piratas inform\u00e1ticos chinos a una infraestructura crucial de Estados Unidos. Este incidente ha generado preocupaci\u00f3n entre los expertos mundiales, que predicen una posible \u201cciberpandemia\u201d en un futuro pr\u00f3ximo.<\/p>\n\n\n\n<p class=\"\">El documento detalla la infiltraci\u00f3n exitosa de cerca de veinte infraestructuras vitales de Estados Unidos, incluidas l\u00edneas el\u00e9ctricas y de agua, as\u00ed como un oleoducto y gasoducto, por parte de piratas inform\u00e1ticos asociados con el Ej\u00e9rcito Popular de Liberaci\u00f3n de China. La operaci\u00f3n, conocida como Volt Typhoon, ha sido desarrollada estrat\u00e9gicamente con el objetivo de inducir p\u00e1nico y desorden, o interrumpir las operaciones log\u00edsticas, en el caso de un potencial conflicto entre Estados Unidos y China en la regi\u00f3n del Pac\u00edfico.<\/p>\n\n\n\n<p class=\"\">Las violaciones actuales parecen estar dirigidas principalmente a la regi\u00f3n del Indo-Pac\u00edfico, incluido Hawaii. Esta regi\u00f3n es importante ya que alberga la Flota del Pac\u00edfico, un puerto y varias instalaciones de suministro. Hasta el momento, no se han observado interrupciones en ning\u00fan sistema.<\/p><div id=\"globa-217957132\" class=\"globa-content globa-entity-placement\"><a href=\"https:\/\/www.givesendgo.com\/globaleyewitnessnews\" aria-label=\"GEN crowdfunder banner ad\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/globaleyewitnessnews.com\/wp-content\/uploads\/2024\/01\/GEN-Banner-Ad-2.png\" alt=\"GEN crowdfunder banner ad\"  srcset=\"https:\/\/globaleyewitnessnews.com\/wp-content\/uploads\/2024\/01\/GEN-Banner-Ad-2.png 2000w, https:\/\/globaleyewitnessnews.com\/wp-content\/uploads\/2024\/01\/GEN-Banner-Ad-2-300x90.png 300w, https:\/\/globaleyewitnessnews.com\/wp-content\/uploads\/2024\/01\/GEN-Banner-Ad-2-1024x307.png 1024w, https:\/\/globaleyewitnessnews.com\/wp-content\/uploads\/2024\/01\/GEN-Banner-Ad-2-768x230.png 768w, https:\/\/globaleyewitnessnews.com\/wp-content\/uploads\/2024\/01\/GEN-Banner-Ad-2-1536x461.png 1536w, https:\/\/globaleyewitnessnews.com\/wp-content\/uploads\/2024\/01\/GEN-Banner-Ad-2-860x258.png 860w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" width=\"2000\" height=\"600\"   \/><\/a><\/div>\n\n\n\n<p class=\"\">Seg\u00fan varios internautas, la investigaci\u00f3n record\u00f3 las <a href=\"https:\/\/frontline.news\/post\/world-economic-forum-warns-of-cyber-pandemic-within-two-years\">predicciones<\/a> del Foro Econ\u00f3mico Mundial (WEF) sobre una \u201cciberpandemia\u201d para 2025.<\/p>\n\n\n\n<p class=\"\">\u201cEl hallazgo m\u00e1s sorprendente que hemos encontrado es que el 93 por ciento de los l\u00edderes cibern\u00e9ticos y el 86 por ciento de los l\u00edderes de empresas cibern\u00e9ticas creen que la inestabilidad geopol\u00edtica hace que sea probable que se produzca un evento cibern\u00e9tico catastr\u00f3fico en los pr\u00f3ximos dos a\u00f1os,\u201d dijo el a\u00f1o pasado el director general de WEF, Jeremy Jurgens, a periodistas en la cumbre del Foro Econ\u00f3mico Mundial en Davos. \u201cEsto supera con creces todo lo que hemos visto en encuestas anteriores.\u201d<\/p>\n\n\n\n<p class=\"\">En un <a href=\"https:\/\/www.weforum.org\/videos\/a-cyber-attack-with-covid-like-characteristics\">video<\/a> publicado en 2021, el Foro Econ\u00f3mico Mundial emiti\u00f3 una advertencia sobre un posible ciberataque con \u201ccaracter\u00edsticas similares a las de COVID\u201d. WEF plante\u00f3 que un ataque de este tipo podr\u00eda tener la capacidad de propagarse m\u00e1s r\u00e1pida y ampliamente que cualquier virus biol\u00f3gico. La empresa afirm\u00f3 que \u201cla \u00fanica forma de detener la propagaci\u00f3n exponencial de una amenaza cibern\u00e9tica similar a COVID es desconectar completamente los millones de dispositivos vulnerables entre s\u00ed y de Internet. Todo esto en cuesti\u00f3n de d\u00edas.\u201d <\/p>\n\n\n\n<p class=\"\">En 2019, el Foro Econ\u00f3mico Mundial fue coanfitri\u00f3n del <a href=\"https:\/\/centerforhealthsecurity.org\/our-work\/tabletop-exercises\/event-201-pandemic-tabletop-exercise#scenario\">Evento 201<\/a>, un ejercicio de simulaci\u00f3n que replic\u00f3 la propagaci\u00f3n de una infecci\u00f3n respiratoria del SARS en todo el mundo. Ese mismo a\u00f1o, el Foro Econ\u00f3mico Mundial colabor\u00f3 con INTERPOL y una entidad llamada BI.ZONE para organizar Cyber Polygon, un evento que simul\u00f3 un ciberataque significativo.<\/p>\n\n\n\n<p class=\"\">El sitio web de Cyber Polygon lo describe como un ejercicio mundial anual con el objetivo de mejorar la ciberresiliencia global. Sin embargo, solo se ha ejecutado tres veces, y la m\u00e1s reciente ocurri\u00f3 en 2021. El evento estaba originalmente planeado para julio del a\u00f1o anterior, pero se <a href=\"https:\/\/cyberpolygon.com\/news\/cyber-polygon-postponed\/\">retras\u00f3<\/a> inesperadamente sin una fecha de reprogramaci\u00f3n espec\u00edfica.<\/p>\n\n\n\n<p class=\"\">La duraci\u00f3n de cada ejercicio de Cyber Polygon fue de 24 horas, durante las cuales se llev\u00f3 a cabo un ciberataque simulado contra una empresa o un banco con el objetivo de conseguir o comprometer los datos de los clientes. Al Equipo Azul se le asign\u00f3 la responsabilidad de anticiparse y contrarrestar el ataque iniciado por el Equipo Rojo.<\/p>\n\n\n\n<p class=\"\">Los participantes proced\u00edan de diversas \u00e1reas, como organizaciones gubernamentales, atenci\u00f3n de salud, educaci\u00f3n y otros campos. La mayor\u00eda de las personas proced\u00edan de empresas financieras, seguidas de cerca por el sector inform\u00e1tico. La polic\u00eda tuvo una participaci\u00f3n significativamente baja.<\/p>\n\n\n\n<p class=\"\">Existe una creencia generalizada de que la ciberpandemia puede servir como justificaci\u00f3n para la implementaci\u00f3n de pol\u00edticas globalistas.<\/p>\n\n\n\n<p class=\"\">El reporte de Cyber Polygon sobre el ejercicio de 2020 <a href=\"https:\/\/cyberpolygon.com\/upload\/Cyber_Polygon_report_results_2020_EN_v1_1.pdf\">sugiri\u00f3<\/a> que los gobiernos deber\u00edan tomar medidas para controlar la privacidad e implementar identificaciones digitales:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"\"><em>Los gobiernos deben adaptarse m\u00e1s r\u00e1pidamente a los cambios en curso: no s\u00f3lo para buscar nuevas herramientas y formas de interactuar con personas y empresas, sino tambi\u00e9n para garantizar la seguridad de dicha interacci\u00f3n. Una identidad digital puede convertirse en una de las formas efectivas de comunicaci\u00f3n entre el Estado y los ciudadanos individuales. Sin embargo, esto s\u00f3lo es posible siempre que la privacidad y la protecci\u00f3n de datos est\u00e9n adecuadamente reguladas.<\/em><\/p>\n<\/blockquote>\n\n\n\n<p class=\"\">Las identificaciones digitales y los pagos digitales desempe\u00f1an un <a href=\"https:\/\/www.weforum.org\/agenda\/2020\/08\/harnessing-the-power-of-digital-id\/\">papel<\/a> crucial en la Agenda 2030 del Foro Econ\u00f3mico Mundial. El grupo se hizo cargo del desarrollo de las identificaciones digitales en 2020 al convocar a gobiernos y empresas de tecnolog\u00eda para establecer la Carta de las Naciones \u00c1giles. La carta <a href=\"https:\/\/frontline.news\/post\/governments-tech-giants-began-developing-digital-i-ds-in-2020-report-reveals\">destac\u00f3<\/a> el desarrollo de una identificaci\u00f3n digital, a veces conocida como \u201ccredenciales digitales\u201d, como una iniciativa clave. Esta identificaci\u00f3n digital ser\u00eda requerida por los ciudadanos para acceder a servicios tanto gubernamentales como privados.<\/p>\n\n\n\n<p class=\"\">A Canad\u00e1 se le asign\u00f3 la responsabilidad de liderar el esfuerzo. Last year Canada&#8217;s Newfoundland and Labrador Digital Government Minister Sarah Stoodley, who is responsible for the development of digital IDs, <a href=\"https:\/\/frontline.news\/post\/canada-minister-confirms-vaccine-passports-paved-way-for-digital-id\">confirmed<\/a> that vaccine passports serve as a preliminary step towards the implementation of digital IDs.<\/p>\n\n\n\n<p class=\"\">Tras la simulaci\u00f3n de 2021, Cyber Polygon sugiri\u00f3 la implementaci\u00f3n de monedas digitales, como las monedas digitales del banco central (<a href=\"https:\/\/frontline.news\/post\/imf-central-banks-may-control-cbdc-transactions\">CBDC<\/a>), como protecci\u00f3n adicional contra una posible ciberpandemia.<\/p>\n\n\n\n<p class=\"\">\u201cLa tarea de los bancos centrales es mantener estable el sistema monetario. Para lograrlo, los bancos centrales deben estar en el centro de los cambios en el sector financiero, deben ampliar la funcionalidad del dinero y de la econom\u00eda, que est\u00e1 cada vez m\u00e1s digitalizada\u201d, dijo Cyber Polygon en un <a href=\"https:\/\/2021.cyberpolygon.com\/upload\/media\/Cyber_Polygon_2021_Report_EN.pdf\">informe <\/a>de la simulaci\u00f3n de 2021.<\/p>\n\n\n\n<p class=\"\">Visa y MasterCard, que participaron en las simulaciones, declararon posteriormente que est\u00e1n haciendo preparativos para respaldar <a href=\"https:\/\/www.investopedia.com\/terms\/s\/stablecoin.asp\">stablecoins<\/a> y las CBDC.<\/p>\n\n\n\n<p class=\"\">\u201cEn un mundo altamente interconectado, un solo ciberataque puede propagarse exponencialmente por toda la comunidad global,\u201d afirma el informe Cyber Polygon.<\/p>\n\n\n\n<p class=\"\">En marzo, Joe Biden hizo una <a href=\"https:\/\/frontline.news\/post\/biden-says-cyberattack-coming-calls-for-new-world-order\">declaraci\u00f3n<\/a> confirmando la probabilidad de un importante ataque cibern\u00e9tico. Expres\u00f3 su creencia de que Rusia, un pa\u00eds que particip\u00f3 activamente en los ejercicios de Cyber Polygon, ser\u00eda el probable iniciador de tal ataque. China no particip\u00f3.<\/p>\n\n\n\n<p class=\"\">Ese mismo d\u00eda, Biden abog\u00f3 por un \u201cnuevo orden mundial.\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un art\u00edculo reciente de Washington Post ha destacado una significativa intrusi\u00f3n cibern\u00e9tica llevada a cabo por piratas inform\u00e1ticos chinos a una infraestructura crucial de Estados Unidos. Este incidente ha generado preocupaci\u00f3n entre los expertos mundiales, que predicen una posible \u201cciberpandemia\u201d en un futuro pr\u00f3ximo. El documento detalla la infiltraci\u00f3n exitosa de cerca de veinte infraestructuras [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3288,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","wds_primary_category":0,"footnotes":""},"categories":[137],"tags":[236,148,251],"class_list":{"0":"post-5444","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mundo","8":"tag-china-es","9":"tag-globalismo-es","10":"tag-tecnologia"},"_links":{"self":[{"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/posts\/5444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/comments?post=5444"}],"version-history":[{"count":4,"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/posts\/5444\/revisions"}],"predecessor-version":[{"id":6162,"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/posts\/5444\/revisions\/6162"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/media\/3288"}],"wp:attachment":[{"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/media?parent=5444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/categories?post=5444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/tags?post=5444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}