{"id":12470,"date":"2024-03-21T11:19:41","date_gmt":"2024-03-21T09:19:41","guid":{"rendered":"https:\/\/globaleyewitnessnews.com\/video-agitador-venezolano-aconseja-a-ilegales-como-aprovecharse-de-la-ley-para-robar-casas-estadounidenses\/"},"modified":"2024-04-03T15:15:20","modified_gmt":"2024-04-03T13:15:20","slug":"video-agitador-venezolano-aconseja-a-ilegales-como-aprovecharse-de-la-ley-para-robar-casas-estadounidenses","status":"publish","type":"post","link":"https:\/\/globaleyewitnessnews.com\/es\/video-agitador-venezolano-aconseja-a-ilegales-como-aprovecharse-de-la-ley-para-robar-casas-estadounidenses\/","title":{"rendered":"Video: Agitador venezolano aconseja ilegales c\u00f3mo aprovecharse de la ley para apropiarse de casas estadounidenses"},"content":{"rendered":"\n<p>Un v\u00eddeo de un agitador profesional venezolano que aconseja a ilegales c\u00f3mo aprovechar las leyes de ocupaci\u00f3n ilegal para robar viviendas en Estados Unidos est\u00e1 atrayendo amplia atenci\u00f3n, lo que ha llevado a algunos a preguntarse por cu\u00e1nto tiempo los estadounidenses seguir\u00e1n aceptando el status quo.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-rumble-com wp-block-embed-rumble-com\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" title=\"Venezuelan Advises Illegals how to take over American Homes via Squatter Laws\" src=\"https:\/\/rumble.com\/embed\/v4huf82\/?pub=4#?secret=xzhK9zQ5lT\" data-secret=\"xzhK9zQ5lT\" width=\"576\" height=\"1024\" frameborder=\"0\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>En el v\u00eddeo, el agitador dice haber \u201cpensado en invadir una casa en United States.\u201d<\/p>\n\n\n\n<p>El contin\u00faa: \u201cMe enter\u00e9 que existe una ley que dice que si una casa no est\u00e1 habitada, podemos expropiarla. Aqu\u00ed en Estados Unidos tambi\u00e9n se aplica la invasi\u00f3n de terreno. Creo que ese ser\u00e1 mi pr\u00f3ximo negocio, invadir casas abandonadas.<\/p><div id=\"globa-881939487\" class=\"globa-content globa-entity-placement\"><a href=\"https:\/\/www.givesendgo.com\/globaleyewitnessnews\" aria-label=\"GEN crowdfunder banner ad\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/globaleyewitnessnews.com\/wp-content\/uploads\/2024\/01\/GEN-Banner-Ad-2.png\" alt=\"GEN crowdfunder banner ad\"  srcset=\"https:\/\/globaleyewitnessnews.com\/wp-content\/uploads\/2024\/01\/GEN-Banner-Ad-2.png 2000w, https:\/\/globaleyewitnessnews.com\/wp-content\/uploads\/2024\/01\/GEN-Banner-Ad-2-300x90.png 300w, https:\/\/globaleyewitnessnews.com\/wp-content\/uploads\/2024\/01\/GEN-Banner-Ad-2-1024x307.png 1024w, https:\/\/globaleyewitnessnews.com\/wp-content\/uploads\/2024\/01\/GEN-Banner-Ad-2-768x230.png 768w, https:\/\/globaleyewitnessnews.com\/wp-content\/uploads\/2024\/01\/GEN-Banner-Ad-2-1536x461.png 1536w, https:\/\/globaleyewitnessnews.com\/wp-content\/uploads\/2024\/01\/GEN-Banner-Ad-2-860x258.png 860w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" width=\"2000\" height=\"600\"   \/><\/a><\/div>\n\n\n\n<p>\u201cMe he buscado unos c\u00f3digos con mis amigos africanos y me dijeron que ya llevan como siete casas expropiadas.<\/p>\n\n\n\n<p>\u201cComo dice el dicho, hay que buscar la vuelta, y la vuelta horita mismo es invadir casas. Ya que nos encontramos en situaci\u00f3n de calle, y es la \u00fanica manera que tenemos para no vivir en la calle y no ser una carga p\u00fablica. <\/p>\n\n\n\n<p>\u201cLa ley dice que las casas abandonadas, deterioradas, y que est\u00e9n en mal estado, podemos llegar y repararlas, vivir en ellas y si podemos, venderla, hasta pedir cr\u00e9ditos con ella.\u201d<\/p>\n\n\n\n<p>Los internautas identificaron al operativo por un v\u00eddeo anterior en el que explica c\u00f3mo una beb\u00e9, que \u00e9l dice que es su hija, es su \u201cmina de oro\u201d: \u201cLa vuelta es tener hijos en los Estados Unidos.\u201d<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-rumble-com wp-block-embed-rumble-com\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" title=\"Illegal Immigrant Explains how his Baby is his \u201cGold Mine\u201d in the United States - \u201cThe Trick is to have Children in the United States\u201d\" src=\"https:\/\/rumble.com\/embed\/v4cxq90\/?pub=4#?secret=QWkXF8Xo2s\" data-secret=\"QWkXF8Xo2s\" width=\"624\" height=\"848\" frameborder=\"0\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">This will continue in Biden\u2019s America.  When will American citizens say enough?<\/p>&mdash; Juanita Broaddrick (@atensnut) <a href=\"https:\/\/twitter.com\/atensnut\/status\/1770495766227763235?ref_src=twsrc%5Etfw\">March 20, 2024<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Un v\u00eddeo de un agitador profesional venezolano que aconseja a ilegales c\u00f3mo aprovechar las leyes de ocupaci\u00f3n ilegal para robar viviendas en Estados Unidos est\u00e1 atrayendo amplia atenci\u00f3n, lo que ha llevado a algunos a preguntarse por cu\u00e1nto tiempo los estadounidenses seguir\u00e1n aceptando el status quo. En el v\u00eddeo, el agitador dice haber \u201cpensado en [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":12305,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","wds_primary_category":0,"footnotes":""},"categories":[136],"tags":[329,330,148,328,327],"class_list":{"0":"post-12470","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-locales","8":"tag-agitador-marxista","9":"tag-entrada-ilegal","10":"tag-globalismo-es","11":"tag-inmigrantes-ilegales","12":"tag-invasores"},"_links":{"self":[{"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/posts\/12470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/comments?post=12470"}],"version-history":[{"count":5,"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/posts\/12470\/revisions"}],"predecessor-version":[{"id":12601,"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/posts\/12470\/revisions\/12601"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/media\/12305"}],"wp:attachment":[{"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/media?parent=12470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/categories?post=12470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/tags?post=12470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}