{"id":12110,"date":"2024-03-19T16:23:11","date_gmt":"2024-03-19T14:23:11","guid":{"rendered":"https:\/\/globaleyewitnessnews.com\/gigante-alimentario-cierra-mas-instalaciones-de-productos-carnicos-en-pro-de-alimento-a-base-de-insectos\/"},"modified":"2024-03-20T12:00:20","modified_gmt":"2024-03-20T10:00:20","slug":"gigante-alimentario-cierra-mas-instalaciones-de-productos-carnicos-en-pro-de-alimento-a-base-de-insectos","status":"publish","type":"post","link":"https:\/\/globaleyewitnessnews.com\/es\/gigante-alimentario-cierra-mas-instalaciones-de-productos-carnicos-en-pro-de-alimento-a-base-de-insectos\/","title":{"rendered":"Gigante alimentario cierra m\u00e1s instalaciones de productos c\u00e1rnicos en pro de alimento a base de insectos"},"content":{"rendered":"\n<p>Tyson Foods anunci\u00f3 la semana pasada que cerrar\u00e1 su planta de carne de cerdo en Perry, Iowa, dejando a m\u00e1s de 1.000 trabajadores enfrent\u00e1ndose al desempleo.<\/p>\n\n\n\n<p>El a\u00f1o pasado la empresa cerr\u00f3 dos plantas av\u00edcolas en Virginia y Arkansas. El gigante alimentario dijo que espera cerrar al menos tres instalaciones c\u00e1rnicas m\u00e1s en 2024, <a href=\"https:\/\/www.usatoday.com\/story\/money\/food\/2024\/03\/12\/tyson-plant-closing-perry-iowa\/72941284007\/\">seg\u00fan<\/a> <em>USA Today<\/em>. <\/p>\n\n\n\n<p>Si bien a\u00fan no ha confirmado el motivo de los cierres, la empresa parece estar alej\u00e1ndose de la producci\u00f3n de carne, que se considera una amenaza para el medio ambiente debido a las emisiones del ganado. En su lugar, Tyson Foods est\u00e1 invirtiendo en una opci\u00f3n m\u00e1s respetuosa con el medio ambiente \u2014 los insectos. <\/p><div id=\"globa-888079865\" class=\"globa-content globa-entity-placement\"><a href=\"https:\/\/www.givesendgo.com\/globaleyewitnessnews\" aria-label=\"GEN crowdfunder banner ad\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/globaleyewitnessnews.com\/wp-content\/uploads\/2024\/01\/GEN-Banner-Ad-2.png\" alt=\"GEN crowdfunder banner ad\"  srcset=\"https:\/\/globaleyewitnessnews.com\/wp-content\/uploads\/2024\/01\/GEN-Banner-Ad-2.png 2000w, https:\/\/globaleyewitnessnews.com\/wp-content\/uploads\/2024\/01\/GEN-Banner-Ad-2-300x90.png 300w, https:\/\/globaleyewitnessnews.com\/wp-content\/uploads\/2024\/01\/GEN-Banner-Ad-2-1024x307.png 1024w, https:\/\/globaleyewitnessnews.com\/wp-content\/uploads\/2024\/01\/GEN-Banner-Ad-2-768x230.png 768w, https:\/\/globaleyewitnessnews.com\/wp-content\/uploads\/2024\/01\/GEN-Banner-Ad-2-1536x461.png 1536w, https:\/\/globaleyewitnessnews.com\/wp-content\/uploads\/2024\/01\/GEN-Banner-Ad-2-860x258.png 860w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" width=\"2000\" height=\"600\"   \/><\/a><\/div>\n\n\n\n<p>En octubre, Tyson Foods anunci\u00f3 su asociaci\u00f3n con <em>Protix<\/em>, una empresa de alimentos a base de insectos ubicada en los Pa\u00edses Bajos. El gigante alimentario revel\u00f3 que las dos empresas decidieron construir una gran instalaci\u00f3n que se utilizar\u00e1 para producir alimento a base de insectos, adem\u00e1s de una inversi\u00f3n financiera en Protix. <\/p>\n\n\n\n<p>\u201cLa instalaci\u00f3n que se construir\u00e1 en los EE.UU. albergar\u00e1 un sistema cerrado para respaldar todos los aspectos de la producci\u00f3n de prote\u00ednas de insectos, incluida la reproducci\u00f3n, incubaci\u00f3n y eclosi\u00f3n de larvas de insectos,\u201d dijo Tyson Foods en un <a href=\"https:\/\/www.tysonfoods.com\/news\/news-releases\/2023\/10\/tyson-foods-announces-partnership-protix-more-sustainable-protein\" target=\"_blank\" rel=\"noreferrer noopener\">comunicado.<\/a> \u201cAdem\u00e1s de los ingredientes para las industrias de la acuicultura y los alimentos para mascotas, las larvas procesadas tambi\u00e9n se pueden utilizar como ingredientes en alimento para ganado y plantas.\u201d<\/p>\n\n\n\n<p>Protix, que fue <a href=\"https:\/\/protix.eu\/wp-content\/uploads\/Press-release-2015-Technology-Pioneer.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">nombrado<\/a> uno de los pioneros tecnol\u00f3gicos del Foro Econ\u00f3mico Mundial en 2015, produce m\u00e1s de 14.000 toneladas m\u00e9tricas de alimento a base de insectos anualmente para \u201cluchar contra el cambio clim\u00e1tico.\u201d Los gobiernos globalistas y el Foro Econ\u00f3mico Mundial (FEM), que dan la <a href=\"https:\/\/www.weforum.org\/agenda\/2018\/07\/good-grub-why-we-might-be-eating-insects-soon\">bienvenida<\/a> al d\u00eda en que \u201ctodos podamos comprar una bolsa de insectos comestibles en nuestro supermercado local,\u201d han hecho de comer insectos para proteger el clima un objetivo importante.<\/p>\n\n\n\n<p>En medio de esto, el inventario estadounidense de carne de res en enero fue el m\u00e1s peque\u00f1o desde 1951, tras disminuir 2% desde 2023, <a href=\"https:\/\/www.fb.org\/market-intel\/u-s-cattle-inventory-smallest-in-73-years#:~:text=The%20inventory%20of%20all%20U.S.,inventory%20from%202022%20to%202023.\">seg\u00fan<\/a> la Federaci\u00f3n Estadounidense de Oficinas Agr\u00edcolas. Reba\u00f1os del a\u00f1o pasado disminuyeron un 4% respecto al a\u00f1o anterior.<\/p>\n\n\n\n<p>El mes pasado, el ganadero de Texas, Shad Sullivan, <a href=\"https:\/\/globaleyewitnessnews.com\/es\/globalistas-crean-crisis-de-carne-advierten-ganaderos\/\" target=\"_blank\" rel=\"noreferrer noopener\">dijo<\/a> a la presentadora de <em>Fox News<\/em>, Laura Ingraham, que esto es intencional y que se est\u00e1 dejando deliberadamente que los ganaderos estadounidenses fracasen como parte de la agenda globalista del \u201ccambio clim\u00e1tico.\u201d<\/p>\n\n\n\n<p>\u201cEl problema extralimitado es el globalismo. Son las \u00e9lites globales las que afirman que el cambio clim\u00e1tico est\u00e1 arruinando el mundo y que debemos implementar la sostenibilidad, que no es m\u00e1s que control de la producci\u00f3n y el consumo en todo el mundo. Vemos que esto sucede por todas partes.   <\/p>\n\n\n\n<p>\u201cDebido a esto, nos estamos integrando verticalmente en nuestro sistema. La industria ganadera es el \u00faltimo basti\u00f3n de la libertad. As\u00ed que, tenemos que tomar el toro por los cuernos, por as\u00ed decirlo, y evitar que estas \u00e9lites globales implementen todo esto. . . regulaciones sostenibles que afirman que el ganado est\u00e1 arruinando el planeta. Y tenemos que detener eso y asegurarnos de que la gente entienda que la sostenibilidad no es m\u00e1s que comunismo,\u201d continu\u00f3 Sullivan. <\/p>\n\n\n\n<p>El ganadero advirti\u00f3 que si no se detiene en seco la agenda globalista, los estadounidenses se ver\u00e1n comiendo insectos en los pr\u00f3ximos 20 a\u00f1os.<\/p>\n\n\n\n<p>\u201cComo sabemos, dos de los cuatro principales empacadores de carne han invertido mucho en los insectos. Uno de ellos, Tyson Foods, anunci\u00f3 <wpcodeself wptype=\"\">hace dos semanas que iban a construir una central de grillos por valor de $500 millones.  Este problema es real, pero es una cuesti\u00f3n de libertad. Ah\u00ed es donde tenemos que centrarnos, tenemos que detener esto.\u201d <\/wpcodeself><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tyson Foods anunci\u00f3 la semana pasada que cerrar\u00e1 su planta de carne de cerdo en Perry, Iowa, dejando a m\u00e1s de 1.000 trabajadores enfrent\u00e1ndose al desempleo. El a\u00f1o pasado la empresa cerr\u00f3 dos plantas av\u00edcolas en Virginia y Arkansas. El gigante alimentario dijo que espera cerrar al menos tres instalaciones c\u00e1rnicas m\u00e1s en 2024, seg\u00fan [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":12030,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","wds_primary_category":0,"footnotes":""},"categories":[136],"tags":[149,148,247],"class_list":{"0":"post-12110","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-locales","8":"tag-cambio-climatico","9":"tag-globalismo-es","10":"tag-nutricion"},"_links":{"self":[{"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/posts\/12110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/comments?post=12110"}],"version-history":[{"count":4,"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/posts\/12110\/revisions"}],"predecessor-version":[{"id":12114,"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/posts\/12110\/revisions\/12114"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/media\/12030"}],"wp:attachment":[{"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/media?parent=12110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/categories?post=12110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globaleyewitnessnews.com\/es\/wp-json\/wp\/v2\/tags?post=12110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}